{"id":15540,"date":"2012-06-11T15:08:03","date_gmt":"2012-06-11T12:08:03","guid":{"rendered":"https:\/\/euea-energyagency.org\/english-category\/news\/events\/the-10th-jrc-workshop-on-energy-efficiency-policies-moscow-25-26-06-2012\/"},"modified":"2012-06-11T15:08:03","modified_gmt":"2012-06-11T12:08:03","slug":"the-10th-jrc-workshop-on-energy-efficiency-policies-moscow-25-26-06-2012","status":"publish","type":"post","link":"https:\/\/euea-energyagency.org\/en\/news\/events\/the-10th-jrc-workshop-on-energy-efficiency-policies-moscow-25-26-06-2012\/","title":{"rendered":"The 10th JRC workshop on Energy Efficiency Policies, Moscow, 25-26 June 2012"},"content":{"rendered":"\n<p>&nbsp;<\/p>\n<p>The main focus will be on the energy efficiency policies and financing mechanisns in EU Candidate Countries and &nbsp;Neighbouring Countries.<\/p>\n<p><a href=\"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2012\/06\/Workshop-Agenda-Moscow-June-2012-draft-4.pdf\">Download Workshop Agenda<\/a><\/p>\n<p>For more information, please contact:<\/p>\n<p>Paolo Bertoldi <br \/> European Commission DG JRC <br \/> Tel. +39 0332 78 9299 (secretary +39 0332 78 9733) <br \/> Fax. +39 0332 78 5869 <br \/> EMAIL: <a href=\"mailto:paolo.bertoldi@ec.europa.eu\"><\/a><a href=\"mailto:paolo.bertoldi@ec.europa.eu\">paolo.bertoldi@ec.europa.eu<\/a> <br \/> URL: <a href=\"http:\/\/re.jrc.ec.europa.eu\/energyefficiency\/\">http:\/\/re.jrc.ec.europa.eu\/energyefficiency\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p><img decoding=\"async\" class=\" alignleft size-full wp-image-15535\" src=\"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2012\/06\/EU_jrc_logo.jpg\" width=\"140\" height=\"60\" alt=\"EU jrc logo\" style=\"margin-right: 10px; float: left;\" \/>The European Commission, through its Joint Research Centre (JRC), has organised in the past a number of workshops dedicated to energy efficiency policies, ESCOs and EPCs, and financial instruments.<\/p>\n<p> This year JRC will organise the workshop on effective energy efficiency policies, new financing instruments, and ESCO on 25-26 June 2012, in Moscow.<\/p>\n","protected":false},"author":132,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[126],"tags":[],"class_list":["post-15540","post","type-post","status-publish","format-standard","hentry","category-events"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>The 10th JRC workshop on Energy Efficiency Policies, Moscow, 25-26 June 2012 - EUEA - European-Ukrainian Energy agency<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/euea-energyagency.org\/en\/news\/events\/the-10th-jrc-workshop-on-energy-efficiency-policies-moscow-25-26-06-2012\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The 10th JRC workshop on Energy Efficiency Policies, Moscow, 25-26 June 2012 - EUEA - European-Ukrainian Energy agency\" \/>\n<meta property=\"og:description\" content=\"The European Commission, through its Joint Research Centre (JRC), has organised in the past a number of workshops dedicated to energy efficiency policies, ESCOs and EPCs, and financial instruments. This year JRC will organise the workshop on effective energy efficiency policies, new financing instruments, and ESCO on 25-26 June 2012, in Moscow.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/euea-energyagency.org\/en\/news\/events\/the-10th-jrc-workshop-on-energy-efficiency-policies-moscow-25-26-06-2012\/\" \/>\n<meta property=\"og:site_name\" content=\"EUEA - European-Ukrainian Energy agency\" \/>\n<meta property=\"article:published_time\" content=\"2012-06-11T12:08:03+00:00\" \/>\n<meta name=\"author\" content=\"Ilya Chepurnoy\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ilya Chepurnoy\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/events\\\/the-10th-jrc-workshop-on-energy-efficiency-policies-moscow-25-26-06-2012\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/events\\\/the-10th-jrc-workshop-on-energy-efficiency-policies-moscow-25-26-06-2012\\\/\"},\"author\":{\"name\":\"Ilya Chepurnoy\",\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#\\\/schema\\\/person\\\/5823158e57aa8ed3e9ea9bd6896d98c1\"},\"headline\":\"The 10th JRC workshop on Energy Efficiency Policies, Moscow, 25-26 June 2012\",\"datePublished\":\"2012-06-11T12:08:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/events\\\/the-10th-jrc-workshop-on-energy-efficiency-policies-moscow-25-26-06-2012\\\/\"},\"wordCount\":64,\"publisher\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#organization\"},\"articleSection\":[\"Events\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/events\\\/the-10th-jrc-workshop-on-energy-efficiency-policies-moscow-25-26-06-2012\\\/\",\"url\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/events\\\/the-10th-jrc-workshop-on-energy-efficiency-policies-moscow-25-26-06-2012\\\/\",\"name\":\"The 10th JRC workshop on Energy Efficiency Policies, Moscow, 25-26 June 2012 - EUEA - European-Ukrainian Energy agency\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#website\"},\"datePublished\":\"2012-06-11T12:08:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/events\\\/the-10th-jrc-workshop-on-energy-efficiency-policies-moscow-25-26-06-2012\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/events\\\/the-10th-jrc-workshop-on-energy-efficiency-policies-moscow-25-26-06-2012\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/events\\\/the-10th-jrc-workshop-on-energy-efficiency-policies-moscow-25-26-06-2012\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043e\u043b\u043e\u0432\u043d\u0430\",\"item\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The 10th JRC workshop on Energy Efficiency Policies, Moscow, 25-26 June 2012\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#website\",\"url\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/\",\"name\":\"EUEA - European-Ukrainian Energy agency\",\"description\":\"EUEA - European-Ukrainian Energy agency\",\"publisher\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#organization\",\"name\":\"EUEA - European-Ukrainian Energy agency\",\"url\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/euea-energyagency.org\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Logo-EUEA-UKR-ENG-_EUEA-logo-white-1.svg\",\"contentUrl\":\"https:\\\/\\\/euea-energyagency.org\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Logo-EUEA-UKR-ENG-_EUEA-logo-white-1.svg\",\"caption\":\"EUEA - European-Ukrainian Energy agency\"},\"image\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#\\\/schema\\\/person\\\/5823158e57aa8ed3e9ea9bd6896d98c1\",\"name\":\"Ilya Chepurnoy\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce4848ab41810e96983ff978ae5d3fe7832dd02ad6e0fec4010da3124b860e9e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce4848ab41810e96983ff978ae5d3fe7832dd02ad6e0fec4010da3124b860e9e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce4848ab41810e96983ff978ae5d3fe7832dd02ad6e0fec4010da3124b860e9e?s=96&d=mm&r=g\",\"caption\":\"Ilya Chepurnoy\"},\"url\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/author\\\/ncar_admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The 10th JRC workshop on Energy Efficiency Policies, Moscow, 25-26 June 2012 - EUEA - European-Ukrainian Energy agency","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/euea-energyagency.org\/en\/news\/events\/the-10th-jrc-workshop-on-energy-efficiency-policies-moscow-25-26-06-2012\/","og_locale":"en_US","og_type":"article","og_title":"The 10th JRC workshop on Energy Efficiency Policies, Moscow, 25-26 June 2012 - EUEA - European-Ukrainian Energy agency","og_description":"The European Commission, through its Joint Research Centre (JRC), has organised in the past a number of workshops dedicated to energy efficiency policies, ESCOs and EPCs, and financial instruments. This year JRC will organise the workshop on effective energy efficiency policies, new financing instruments, and ESCO on 25-26 June 2012, in Moscow.","og_url":"https:\/\/euea-energyagency.org\/en\/news\/events\/the-10th-jrc-workshop-on-energy-efficiency-policies-moscow-25-26-06-2012\/","og_site_name":"EUEA - European-Ukrainian Energy agency","article_published_time":"2012-06-11T12:08:03+00:00","author":"Ilya Chepurnoy","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Ilya Chepurnoy"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/euea-energyagency.org\/en\/news\/events\/the-10th-jrc-workshop-on-energy-efficiency-policies-moscow-25-26-06-2012\/#article","isPartOf":{"@id":"https:\/\/euea-energyagency.org\/en\/news\/events\/the-10th-jrc-workshop-on-energy-efficiency-policies-moscow-25-26-06-2012\/"},"author":{"name":"Ilya Chepurnoy","@id":"https:\/\/euea-energyagency.org\/uk\/#\/schema\/person\/5823158e57aa8ed3e9ea9bd6896d98c1"},"headline":"The 10th JRC workshop on Energy Efficiency Policies, Moscow, 25-26 June 2012","datePublished":"2012-06-11T12:08:03+00:00","mainEntityOfPage":{"@id":"https:\/\/euea-energyagency.org\/en\/news\/events\/the-10th-jrc-workshop-on-energy-efficiency-policies-moscow-25-26-06-2012\/"},"wordCount":64,"publisher":{"@id":"https:\/\/euea-energyagency.org\/uk\/#organization"},"articleSection":["Events"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/euea-energyagency.org\/en\/news\/events\/the-10th-jrc-workshop-on-energy-efficiency-policies-moscow-25-26-06-2012\/","url":"https:\/\/euea-energyagency.org\/en\/news\/events\/the-10th-jrc-workshop-on-energy-efficiency-policies-moscow-25-26-06-2012\/","name":"The 10th JRC workshop on Energy Efficiency Policies, Moscow, 25-26 June 2012 - EUEA - European-Ukrainian Energy agency","isPartOf":{"@id":"https:\/\/euea-energyagency.org\/uk\/#website"},"datePublished":"2012-06-11T12:08:03+00:00","breadcrumb":{"@id":"https:\/\/euea-energyagency.org\/en\/news\/events\/the-10th-jrc-workshop-on-energy-efficiency-policies-moscow-25-26-06-2012\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/euea-energyagency.org\/en\/news\/events\/the-10th-jrc-workshop-on-energy-efficiency-policies-moscow-25-26-06-2012\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/euea-energyagency.org\/en\/news\/events\/the-10th-jrc-workshop-on-energy-efficiency-policies-moscow-25-26-06-2012\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043e\u043b\u043e\u0432\u043d\u0430","item":"https:\/\/euea-energyagency.org\/uk\/"},{"@type":"ListItem","position":2,"name":"The 10th JRC workshop on Energy Efficiency Policies, Moscow, 25-26 June 2012"}]},{"@type":"WebSite","@id":"https:\/\/euea-energyagency.org\/uk\/#website","url":"https:\/\/euea-energyagency.org\/uk\/","name":"EUEA - European-Ukrainian Energy agency","description":"EUEA - European-Ukrainian Energy agency","publisher":{"@id":"https:\/\/euea-energyagency.org\/uk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/euea-energyagency.org\/uk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/euea-energyagency.org\/uk\/#organization","name":"EUEA - European-Ukrainian Energy agency","url":"https:\/\/euea-energyagency.org\/uk\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/euea-energyagency.org\/uk\/#\/schema\/logo\/image\/","url":"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2026\/02\/Logo-EUEA-UKR-ENG-_EUEA-logo-white-1.svg","contentUrl":"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2026\/02\/Logo-EUEA-UKR-ENG-_EUEA-logo-white-1.svg","caption":"EUEA - European-Ukrainian Energy agency"},"image":{"@id":"https:\/\/euea-energyagency.org\/uk\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/euea-energyagency.org\/uk\/#\/schema\/person\/5823158e57aa8ed3e9ea9bd6896d98c1","name":"Ilya Chepurnoy","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/ce4848ab41810e96983ff978ae5d3fe7832dd02ad6e0fec4010da3124b860e9e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ce4848ab41810e96983ff978ae5d3fe7832dd02ad6e0fec4010da3124b860e9e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ce4848ab41810e96983ff978ae5d3fe7832dd02ad6e0fec4010da3124b860e9e?s=96&d=mm&r=g","caption":"Ilya Chepurnoy"},"url":"https:\/\/euea-energyagency.org\/en\/author\/ncar_admin\/"}]}},"_links":{"self":[{"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/posts\/15540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/users\/132"}],"replies":[{"embeddable":true,"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/comments?post=15540"}],"version-history":[{"count":0,"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/posts\/15540\/revisions"}],"wp:attachment":[{"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/media?parent=15540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/categories?post=15540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/tags?post=15540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}