{"id":17904,"date":"2014-11-19T15:14:26","date_gmt":"2014-11-19T13:14:26","guid":{"rendered":"https:\/\/euea-energyagency.org\/english-category\/news\/events\/business-seminar-austrian-showcase-ukraine-energy-efficiency-renewable-energy-december-4-kyiv\/"},"modified":"2014-11-19T15:14:26","modified_gmt":"2014-11-19T13:14:26","slug":"business-seminar-austrian-showcase-ukraine-energy-efficiency-renewable-energy-december-4-kyiv","status":"publish","type":"post","link":"https:\/\/euea-energyagency.org\/en\/news\/events\/business-seminar-austrian-showcase-ukraine-energy-efficiency-renewable-energy-december-4-kyiv\/","title":{"rendered":"Business Seminar Austrian Showcase Ukraine: Energy Efficiency. Renewable energy, December 4, Kyiv"},"content":{"rendered":"<p><img decoding=\"async\" class=\" alignleft size-full wp-image-15350\" src=\"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2012\/05\/events_calendar.jpg\" width=\"140\" height=\"140\" alt=\"events calendar\"  \/>Business Seminar will be held on December 4, 2014.<\/p>\n<p>Companies and organizations that would like to become more familiar with Austrian practices in energy efficiency and renewable energy fields are welcomed to participate.<\/p>\n<p>Participants will have an opportunity to establish business contacts with <span ><strong><a href=\"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2014\/11\/spysok_firm.pdf\">Austrian companies<\/a><\/strong><\/span> (information in Ukrainian) of mentioned sectors.<\/p>\n<p>The event will be held at Radisson Blu Hotel, Kyiv, 22 Yaroslav Val street, Hall &#8220;EMBASSY SUITE&#8221;.<\/p>\n<p>The program of the event is available <span ><strong><a href=\"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2014\/11\/Programm_0412_uk_.pdf\">HERE<\/a><\/strong><\/span> in Ukrainian. Working languages: Ukrainian and German.<\/p>\n<p>The event is free with mandatory registration. Registration form can be downloaded <span ><strong><a href=\"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2014\/11\/registration_form.doc\">HERE<\/a><\/strong><\/span> (in Ukrainian).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Business Seminar will be held on December 4, 2014. Companies and organizations that would like to become more familiar with [&hellip;]<\/p>\n","protected":false},"author":136,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[126],"tags":[],"class_list":["post-17904","post","type-post","status-publish","format-standard","hentry","category-events"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Business Seminar Austrian Showcase Ukraine: Energy Efficiency. Renewable energy, December 4, Kyiv - EUEA - European-Ukrainian Energy agency<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/euea-energyagency.org\/en\/news\/events\/business-seminar-austrian-showcase-ukraine-energy-efficiency-renewable-energy-december-4-kyiv\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Business Seminar Austrian Showcase Ukraine: Energy Efficiency. Renewable energy, December 4, Kyiv - EUEA - European-Ukrainian Energy agency\" \/>\n<meta property=\"og:description\" content=\"Business Seminar will be held on December 4, 2014. Companies and organizations that would like to become more familiar with [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/euea-energyagency.org\/en\/news\/events\/business-seminar-austrian-showcase-ukraine-energy-efficiency-renewable-energy-december-4-kyiv\/\" \/>\n<meta property=\"og:site_name\" content=\"EUEA - European-Ukrainian Energy agency\" \/>\n<meta property=\"article:published_time\" content=\"2014-11-19T13:14:26+00:00\" \/>\n<meta name=\"author\" content=\"Natalia Tatarchuk\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Natalia Tatarchuk\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/events\\\/business-seminar-austrian-showcase-ukraine-energy-efficiency-renewable-energy-december-4-kyiv\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/events\\\/business-seminar-austrian-showcase-ukraine-energy-efficiency-renewable-energy-december-4-kyiv\\\/\"},\"author\":{\"name\":\"Natalia Tatarchuk\",\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#\\\/schema\\\/person\\\/a0e8854c86806df275b9e4f1c2e6e56e\"},\"headline\":\"Business Seminar Austrian Showcase Ukraine: Energy Efficiency. Renewable energy, December 4, Kyiv\",\"datePublished\":\"2014-11-19T13:14:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/events\\\/business-seminar-austrian-showcase-ukraine-energy-efficiency-renewable-energy-december-4-kyiv\\\/\"},\"wordCount\":106,\"publisher\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/events\\\/business-seminar-austrian-showcase-ukraine-energy-efficiency-renewable-energy-december-4-kyiv\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/euea-energyagency.org\\\/wp-content\\\/uploads\\\/2012\\\/05\\\/events_calendar.jpg\",\"articleSection\":[\"Events\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/events\\\/business-seminar-austrian-showcase-ukraine-energy-efficiency-renewable-energy-december-4-kyiv\\\/\",\"url\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/events\\\/business-seminar-austrian-showcase-ukraine-energy-efficiency-renewable-energy-december-4-kyiv\\\/\",\"name\":\"Business Seminar Austrian Showcase Ukraine: Energy Efficiency. Renewable energy, December 4, Kyiv - EUEA - European-Ukrainian Energy agency\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/events\\\/business-seminar-austrian-showcase-ukraine-energy-efficiency-renewable-energy-december-4-kyiv\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/events\\\/business-seminar-austrian-showcase-ukraine-energy-efficiency-renewable-energy-december-4-kyiv\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/euea-energyagency.org\\\/wp-content\\\/uploads\\\/2012\\\/05\\\/events_calendar.jpg\",\"datePublished\":\"2014-11-19T13:14:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/events\\\/business-seminar-austrian-showcase-ukraine-energy-efficiency-renewable-energy-december-4-kyiv\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/events\\\/business-seminar-austrian-showcase-ukraine-energy-efficiency-renewable-energy-december-4-kyiv\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/events\\\/business-seminar-austrian-showcase-ukraine-energy-efficiency-renewable-energy-december-4-kyiv\\\/#primaryimage\",\"url\":\"https:\\\/\\\/euea-energyagency.org\\\/wp-content\\\/uploads\\\/2012\\\/05\\\/events_calendar.jpg\",\"contentUrl\":\"https:\\\/\\\/euea-energyagency.org\\\/wp-content\\\/uploads\\\/2012\\\/05\\\/events_calendar.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/events\\\/business-seminar-austrian-showcase-ukraine-energy-efficiency-renewable-energy-december-4-kyiv\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043e\u043b\u043e\u0432\u043d\u0430\",\"item\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Business Seminar Austrian Showcase Ukraine: Energy Efficiency. Renewable energy, December 4, Kyiv\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#website\",\"url\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/\",\"name\":\"EUEA - European-Ukrainian Energy agency\",\"description\":\"EUEA - European-Ukrainian Energy agency\",\"publisher\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#organization\",\"name\":\"EUEA - European-Ukrainian Energy agency\",\"url\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/euea-energyagency.org\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Logo-EUEA-UKR-ENG-_EUEA-logo-white-1.svg\",\"contentUrl\":\"https:\\\/\\\/euea-energyagency.org\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Logo-EUEA-UKR-ENG-_EUEA-logo-white-1.svg\",\"caption\":\"EUEA - European-Ukrainian Energy agency\"},\"image\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#\\\/schema\\\/person\\\/a0e8854c86806df275b9e4f1c2e6e56e\",\"name\":\"Natalia Tatarchuk\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9ef82c888699f1acdf80f3e3bc1809edf509b04f3894dabaaf7874906e77df30?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9ef82c888699f1acdf80f3e3bc1809edf509b04f3894dabaaf7874906e77df30?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9ef82c888699f1acdf80f3e3bc1809edf509b04f3894dabaaf7874906e77df30?s=96&d=mm&r=g\",\"caption\":\"Natalia Tatarchuk\"},\"url\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/author\\\/natalia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Business Seminar Austrian Showcase Ukraine: Energy Efficiency. Renewable energy, December 4, Kyiv - EUEA - European-Ukrainian Energy agency","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/euea-energyagency.org\/en\/news\/events\/business-seminar-austrian-showcase-ukraine-energy-efficiency-renewable-energy-december-4-kyiv\/","og_locale":"en_US","og_type":"article","og_title":"Business Seminar Austrian Showcase Ukraine: Energy Efficiency. Renewable energy, December 4, Kyiv - EUEA - European-Ukrainian Energy agency","og_description":"Business Seminar will be held on December 4, 2014. Companies and organizations that would like to become more familiar with [&hellip;]","og_url":"https:\/\/euea-energyagency.org\/en\/news\/events\/business-seminar-austrian-showcase-ukraine-energy-efficiency-renewable-energy-december-4-kyiv\/","og_site_name":"EUEA - European-Ukrainian Energy agency","article_published_time":"2014-11-19T13:14:26+00:00","author":"Natalia Tatarchuk","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Natalia Tatarchuk"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/euea-energyagency.org\/en\/news\/events\/business-seminar-austrian-showcase-ukraine-energy-efficiency-renewable-energy-december-4-kyiv\/#article","isPartOf":{"@id":"https:\/\/euea-energyagency.org\/en\/news\/events\/business-seminar-austrian-showcase-ukraine-energy-efficiency-renewable-energy-december-4-kyiv\/"},"author":{"name":"Natalia Tatarchuk","@id":"https:\/\/euea-energyagency.org\/uk\/#\/schema\/person\/a0e8854c86806df275b9e4f1c2e6e56e"},"headline":"Business Seminar Austrian Showcase Ukraine: Energy Efficiency. Renewable energy, December 4, Kyiv","datePublished":"2014-11-19T13:14:26+00:00","mainEntityOfPage":{"@id":"https:\/\/euea-energyagency.org\/en\/news\/events\/business-seminar-austrian-showcase-ukraine-energy-efficiency-renewable-energy-december-4-kyiv\/"},"wordCount":106,"publisher":{"@id":"https:\/\/euea-energyagency.org\/uk\/#organization"},"image":{"@id":"https:\/\/euea-energyagency.org\/en\/news\/events\/business-seminar-austrian-showcase-ukraine-energy-efficiency-renewable-energy-december-4-kyiv\/#primaryimage"},"thumbnailUrl":"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2012\/05\/events_calendar.jpg","articleSection":["Events"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/euea-energyagency.org\/en\/news\/events\/business-seminar-austrian-showcase-ukraine-energy-efficiency-renewable-energy-december-4-kyiv\/","url":"https:\/\/euea-energyagency.org\/en\/news\/events\/business-seminar-austrian-showcase-ukraine-energy-efficiency-renewable-energy-december-4-kyiv\/","name":"Business Seminar Austrian Showcase Ukraine: Energy Efficiency. Renewable energy, December 4, Kyiv - EUEA - European-Ukrainian Energy agency","isPartOf":{"@id":"https:\/\/euea-energyagency.org\/uk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/euea-energyagency.org\/en\/news\/events\/business-seminar-austrian-showcase-ukraine-energy-efficiency-renewable-energy-december-4-kyiv\/#primaryimage"},"image":{"@id":"https:\/\/euea-energyagency.org\/en\/news\/events\/business-seminar-austrian-showcase-ukraine-energy-efficiency-renewable-energy-december-4-kyiv\/#primaryimage"},"thumbnailUrl":"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2012\/05\/events_calendar.jpg","datePublished":"2014-11-19T13:14:26+00:00","breadcrumb":{"@id":"https:\/\/euea-energyagency.org\/en\/news\/events\/business-seminar-austrian-showcase-ukraine-energy-efficiency-renewable-energy-december-4-kyiv\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/euea-energyagency.org\/en\/news\/events\/business-seminar-austrian-showcase-ukraine-energy-efficiency-renewable-energy-december-4-kyiv\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/euea-energyagency.org\/en\/news\/events\/business-seminar-austrian-showcase-ukraine-energy-efficiency-renewable-energy-december-4-kyiv\/#primaryimage","url":"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2012\/05\/events_calendar.jpg","contentUrl":"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2012\/05\/events_calendar.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/euea-energyagency.org\/en\/news\/events\/business-seminar-austrian-showcase-ukraine-energy-efficiency-renewable-energy-december-4-kyiv\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043e\u043b\u043e\u0432\u043d\u0430","item":"https:\/\/euea-energyagency.org\/uk\/"},{"@type":"ListItem","position":2,"name":"Business Seminar Austrian Showcase Ukraine: Energy Efficiency. Renewable energy, December 4, Kyiv"}]},{"@type":"WebSite","@id":"https:\/\/euea-energyagency.org\/uk\/#website","url":"https:\/\/euea-energyagency.org\/uk\/","name":"EUEA - European-Ukrainian Energy agency","description":"EUEA - European-Ukrainian Energy agency","publisher":{"@id":"https:\/\/euea-energyagency.org\/uk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/euea-energyagency.org\/uk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/euea-energyagency.org\/uk\/#organization","name":"EUEA - European-Ukrainian Energy agency","url":"https:\/\/euea-energyagency.org\/uk\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/euea-energyagency.org\/uk\/#\/schema\/logo\/image\/","url":"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2026\/02\/Logo-EUEA-UKR-ENG-_EUEA-logo-white-1.svg","contentUrl":"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2026\/02\/Logo-EUEA-UKR-ENG-_EUEA-logo-white-1.svg","caption":"EUEA - European-Ukrainian Energy agency"},"image":{"@id":"https:\/\/euea-energyagency.org\/uk\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/euea-energyagency.org\/uk\/#\/schema\/person\/a0e8854c86806df275b9e4f1c2e6e56e","name":"Natalia Tatarchuk","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/9ef82c888699f1acdf80f3e3bc1809edf509b04f3894dabaaf7874906e77df30?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9ef82c888699f1acdf80f3e3bc1809edf509b04f3894dabaaf7874906e77df30?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ef82c888699f1acdf80f3e3bc1809edf509b04f3894dabaaf7874906e77df30?s=96&d=mm&r=g","caption":"Natalia Tatarchuk"},"url":"https:\/\/euea-energyagency.org\/en\/author\/natalia\/"}]}},"_links":{"self":[{"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/posts\/17904","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/users\/136"}],"replies":[{"embeddable":true,"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/comments?post=17904"}],"version-history":[{"count":0,"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/posts\/17904\/revisions"}],"wp:attachment":[{"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/media?parent=17904"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/categories?post=17904"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/tags?post=17904"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}