{"id":18010,"date":"2015-03-11T12:04:32","date_gmt":"2015-03-11T10:04:32","guid":{"rendered":"https:\/\/euea-energyagency.org\/english-category\/news\/events\/workshop-on-energy-efficiency-in-buildings-and-advanced-district-heating-23-march-2015-intercontinental-hotel-kyiv-ukraine\/"},"modified":"2015-03-11T12:04:32","modified_gmt":"2015-03-11T10:04:32","slug":"workshop-on-energy-efficiency-in-buildings-and-advanced-district-heating-23-march-2015-intercontinental-hotel-kyiv-ukraine","status":"publish","type":"post","link":"https:\/\/euea-energyagency.org\/en\/news\/events\/workshop-on-energy-efficiency-in-buildings-and-advanced-district-heating-23-march-2015-intercontinental-hotel-kyiv-ukraine\/","title":{"rendered":"Workshop on Energy Efficiency in Buildings and Advanced District Heating, 23 March 2015, Intercontinental Hotel &#8211; Kyiv, Ukraine"},"content":{"rendered":"<p><img decoding=\"async\" class=\" alignleft size-full wp-image-18005\" src=\"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2015\/03\/IEA_Logo.png\" width=\"140\" height=\"82\" alt=\"IEA Logo\"  \/>Being Informational and Communicational Partner of the event EUEA is glad to invite you to participate in <b>Workshop on Energy Efficiency in Buildings and Advanced District Heating<\/b><b>.<\/b> Held by the International Energy Agency (IEA) in collaboration with the State Agency on Energy&nbsp;<span >Efficiency and Energy Saving of Ukraine (SAEE).<\/span><\/p>\n<p><b><\/b><\/p>\n<p>The overarching aim of the workshop is to provide an opportunity for a selection of key Ukrainian stakeholders and international experts to discuss action options to achieve energy efficiency gains in the buildings sector, including the district heating networks, as well as sharing experiences on regulatory and policy measures that may facilitate energy efficiency technology deployment. This one-day event is composed of four substantive sessions, each involving short presentations from a range of speakers selected on the basis of experiences in supporting policy and technology development in the buildings and\/or district heating sector, thereby contributing to identify priorities and efforts to foster the market uptake of EE technology in the country. Presentations will be followed by interactive roundtable discussion with the panellists.<\/p>\n<p>Participants are kindly requested to <b>register online at&nbsp;<\/b><a href=\"http:\/\/www.iea.org\/training\/eeukraine2015\">www.iea.org\/training\/eeukraine2015<\/a> <b>by Friday 13 March 2015.<\/b><\/p>\n<p>In case of questions, please contact <a href=\"mailto:TechPlatform@iea.org\"><\/a><a href=\"mailto:TechPlatform@iea.org\">TechPlatform@iea.org<\/a><\/p>\n<p>Program of the event is available <strong><span ><a href=\"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2015\/03\/Ukraine_23_March_2015_EE_and_DH_Workshop_Draft_3.5.pdf\">HERE<\/a><\/span><\/strong>.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Being Informational and Communicational Partner of the event EUEA is glad to invite you to participate in Workshop on Energy [&hellip;]<\/p>\n","protected":false},"author":136,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[126],"tags":[],"class_list":["post-18010","post","type-post","status-publish","format-standard","hentry","category-events"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Workshop on Energy Efficiency in Buildings and Advanced District Heating, 23 March 2015, Intercontinental Hotel - Kyiv, Ukraine - EUEA - European-Ukrainian Energy agency<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/euea-energyagency.org\/en\/news\/events\/workshop-on-energy-efficiency-in-buildings-and-advanced-district-heating-23-march-2015-intercontinental-hotel-kyiv-ukraine\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Workshop on Energy Efficiency in Buildings and Advanced District Heating, 23 March 2015, Intercontinental Hotel - Kyiv, Ukraine - EUEA - European-Ukrainian Energy agency\" \/>\n<meta property=\"og:description\" content=\"Being Informational and Communicational Partner of the event EUEA is glad to invite you to participate in Workshop on Energy [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/euea-energyagency.org\/en\/news\/events\/workshop-on-energy-efficiency-in-buildings-and-advanced-district-heating-23-march-2015-intercontinental-hotel-kyiv-ukraine\/\" \/>\n<meta property=\"og:site_name\" content=\"EUEA - European-Ukrainian Energy agency\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-11T10:04:32+00:00\" \/>\n<meta name=\"author\" content=\"Natalia Tatarchuk\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Natalia Tatarchuk\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/events\\\/workshop-on-energy-efficiency-in-buildings-and-advanced-district-heating-23-march-2015-intercontinental-hotel-kyiv-ukraine\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/events\\\/workshop-on-energy-efficiency-in-buildings-and-advanced-district-heating-23-march-2015-intercontinental-hotel-kyiv-ukraine\\\/\"},\"author\":{\"name\":\"Natalia Tatarchuk\",\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#\\\/schema\\\/person\\\/a0e8854c86806df275b9e4f1c2e6e56e\"},\"headline\":\"Workshop on Energy Efficiency in Buildings and Advanced District Heating, 23 March 2015, Intercontinental Hotel &#8211; Kyiv, Ukraine\",\"datePublished\":\"2015-03-11T10:04:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/events\\\/workshop-on-energy-efficiency-in-buildings-and-advanced-district-heating-23-march-2015-intercontinental-hotel-kyiv-ukraine\\\/\"},\"wordCount\":223,\"publisher\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/events\\\/workshop-on-energy-efficiency-in-buildings-and-advanced-district-heating-23-march-2015-intercontinental-hotel-kyiv-ukraine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/euea-energyagency.org\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/IEA_Logo.png\",\"articleSection\":[\"Events\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/events\\\/workshop-on-energy-efficiency-in-buildings-and-advanced-district-heating-23-march-2015-intercontinental-hotel-kyiv-ukraine\\\/\",\"url\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/events\\\/workshop-on-energy-efficiency-in-buildings-and-advanced-district-heating-23-march-2015-intercontinental-hotel-kyiv-ukraine\\\/\",\"name\":\"Workshop on Energy Efficiency in Buildings and Advanced District Heating, 23 March 2015, Intercontinental Hotel - Kyiv, Ukraine - EUEA - European-Ukrainian Energy agency\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/events\\\/workshop-on-energy-efficiency-in-buildings-and-advanced-district-heating-23-march-2015-intercontinental-hotel-kyiv-ukraine\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/events\\\/workshop-on-energy-efficiency-in-buildings-and-advanced-district-heating-23-march-2015-intercontinental-hotel-kyiv-ukraine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/euea-energyagency.org\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/IEA_Logo.png\",\"datePublished\":\"2015-03-11T10:04:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/events\\\/workshop-on-energy-efficiency-in-buildings-and-advanced-district-heating-23-march-2015-intercontinental-hotel-kyiv-ukraine\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/events\\\/workshop-on-energy-efficiency-in-buildings-and-advanced-district-heating-23-march-2015-intercontinental-hotel-kyiv-ukraine\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/events\\\/workshop-on-energy-efficiency-in-buildings-and-advanced-district-heating-23-march-2015-intercontinental-hotel-kyiv-ukraine\\\/#primaryimage\",\"url\":\"https:\\\/\\\/euea-energyagency.org\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/IEA_Logo.png\",\"contentUrl\":\"https:\\\/\\\/euea-energyagency.org\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/IEA_Logo.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/events\\\/workshop-on-energy-efficiency-in-buildings-and-advanced-district-heating-23-march-2015-intercontinental-hotel-kyiv-ukraine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043e\u043b\u043e\u0432\u043d\u0430\",\"item\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Workshop on Energy Efficiency in Buildings and Advanced District Heating, 23 March 2015, Intercontinental Hotel &#8211; Kyiv, Ukraine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#website\",\"url\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/\",\"name\":\"EUEA - European-Ukrainian Energy agency\",\"description\":\"EUEA - European-Ukrainian Energy agency\",\"publisher\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#organization\",\"name\":\"EUEA - European-Ukrainian Energy agency\",\"url\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/euea-energyagency.org\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Logo-EUEA-UKR-ENG-_EUEA-logo-white-1.svg\",\"contentUrl\":\"https:\\\/\\\/euea-energyagency.org\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Logo-EUEA-UKR-ENG-_EUEA-logo-white-1.svg\",\"caption\":\"EUEA - European-Ukrainian Energy agency\"},\"image\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#\\\/schema\\\/person\\\/a0e8854c86806df275b9e4f1c2e6e56e\",\"name\":\"Natalia Tatarchuk\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9ef82c888699f1acdf80f3e3bc1809edf509b04f3894dabaaf7874906e77df30?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9ef82c888699f1acdf80f3e3bc1809edf509b04f3894dabaaf7874906e77df30?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9ef82c888699f1acdf80f3e3bc1809edf509b04f3894dabaaf7874906e77df30?s=96&d=mm&r=g\",\"caption\":\"Natalia Tatarchuk\"},\"url\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/author\\\/natalia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Workshop on Energy Efficiency in Buildings and Advanced District Heating, 23 March 2015, Intercontinental Hotel - Kyiv, Ukraine - EUEA - European-Ukrainian Energy agency","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/euea-energyagency.org\/en\/news\/events\/workshop-on-energy-efficiency-in-buildings-and-advanced-district-heating-23-march-2015-intercontinental-hotel-kyiv-ukraine\/","og_locale":"en_US","og_type":"article","og_title":"Workshop on Energy Efficiency in Buildings and Advanced District Heating, 23 March 2015, Intercontinental Hotel - Kyiv, Ukraine - EUEA - European-Ukrainian Energy agency","og_description":"Being Informational and Communicational Partner of the event EUEA is glad to invite you to participate in Workshop on Energy [&hellip;]","og_url":"https:\/\/euea-energyagency.org\/en\/news\/events\/workshop-on-energy-efficiency-in-buildings-and-advanced-district-heating-23-march-2015-intercontinental-hotel-kyiv-ukraine\/","og_site_name":"EUEA - European-Ukrainian Energy agency","article_published_time":"2015-03-11T10:04:32+00:00","author":"Natalia Tatarchuk","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Natalia Tatarchuk","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/euea-energyagency.org\/en\/news\/events\/workshop-on-energy-efficiency-in-buildings-and-advanced-district-heating-23-march-2015-intercontinental-hotel-kyiv-ukraine\/#article","isPartOf":{"@id":"https:\/\/euea-energyagency.org\/en\/news\/events\/workshop-on-energy-efficiency-in-buildings-and-advanced-district-heating-23-march-2015-intercontinental-hotel-kyiv-ukraine\/"},"author":{"name":"Natalia Tatarchuk","@id":"https:\/\/euea-energyagency.org\/uk\/#\/schema\/person\/a0e8854c86806df275b9e4f1c2e6e56e"},"headline":"Workshop on Energy Efficiency in Buildings and Advanced District Heating, 23 March 2015, Intercontinental Hotel &#8211; Kyiv, Ukraine","datePublished":"2015-03-11T10:04:32+00:00","mainEntityOfPage":{"@id":"https:\/\/euea-energyagency.org\/en\/news\/events\/workshop-on-energy-efficiency-in-buildings-and-advanced-district-heating-23-march-2015-intercontinental-hotel-kyiv-ukraine\/"},"wordCount":223,"publisher":{"@id":"https:\/\/euea-energyagency.org\/uk\/#organization"},"image":{"@id":"https:\/\/euea-energyagency.org\/en\/news\/events\/workshop-on-energy-efficiency-in-buildings-and-advanced-district-heating-23-march-2015-intercontinental-hotel-kyiv-ukraine\/#primaryimage"},"thumbnailUrl":"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2015\/03\/IEA_Logo.png","articleSection":["Events"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/euea-energyagency.org\/en\/news\/events\/workshop-on-energy-efficiency-in-buildings-and-advanced-district-heating-23-march-2015-intercontinental-hotel-kyiv-ukraine\/","url":"https:\/\/euea-energyagency.org\/en\/news\/events\/workshop-on-energy-efficiency-in-buildings-and-advanced-district-heating-23-march-2015-intercontinental-hotel-kyiv-ukraine\/","name":"Workshop on Energy Efficiency in Buildings and Advanced District Heating, 23 March 2015, Intercontinental Hotel - Kyiv, Ukraine - EUEA - European-Ukrainian Energy agency","isPartOf":{"@id":"https:\/\/euea-energyagency.org\/uk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/euea-energyagency.org\/en\/news\/events\/workshop-on-energy-efficiency-in-buildings-and-advanced-district-heating-23-march-2015-intercontinental-hotel-kyiv-ukraine\/#primaryimage"},"image":{"@id":"https:\/\/euea-energyagency.org\/en\/news\/events\/workshop-on-energy-efficiency-in-buildings-and-advanced-district-heating-23-march-2015-intercontinental-hotel-kyiv-ukraine\/#primaryimage"},"thumbnailUrl":"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2015\/03\/IEA_Logo.png","datePublished":"2015-03-11T10:04:32+00:00","breadcrumb":{"@id":"https:\/\/euea-energyagency.org\/en\/news\/events\/workshop-on-energy-efficiency-in-buildings-and-advanced-district-heating-23-march-2015-intercontinental-hotel-kyiv-ukraine\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/euea-energyagency.org\/en\/news\/events\/workshop-on-energy-efficiency-in-buildings-and-advanced-district-heating-23-march-2015-intercontinental-hotel-kyiv-ukraine\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/euea-energyagency.org\/en\/news\/events\/workshop-on-energy-efficiency-in-buildings-and-advanced-district-heating-23-march-2015-intercontinental-hotel-kyiv-ukraine\/#primaryimage","url":"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2015\/03\/IEA_Logo.png","contentUrl":"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2015\/03\/IEA_Logo.png"},{"@type":"BreadcrumbList","@id":"https:\/\/euea-energyagency.org\/en\/news\/events\/workshop-on-energy-efficiency-in-buildings-and-advanced-district-heating-23-march-2015-intercontinental-hotel-kyiv-ukraine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043e\u043b\u043e\u0432\u043d\u0430","item":"https:\/\/euea-energyagency.org\/uk\/"},{"@type":"ListItem","position":2,"name":"Workshop on Energy Efficiency in Buildings and Advanced District Heating, 23 March 2015, Intercontinental Hotel &#8211; Kyiv, Ukraine"}]},{"@type":"WebSite","@id":"https:\/\/euea-energyagency.org\/uk\/#website","url":"https:\/\/euea-energyagency.org\/uk\/","name":"EUEA - European-Ukrainian Energy agency","description":"EUEA - European-Ukrainian Energy agency","publisher":{"@id":"https:\/\/euea-energyagency.org\/uk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/euea-energyagency.org\/uk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/euea-energyagency.org\/uk\/#organization","name":"EUEA - European-Ukrainian Energy agency","url":"https:\/\/euea-energyagency.org\/uk\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/euea-energyagency.org\/uk\/#\/schema\/logo\/image\/","url":"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2026\/02\/Logo-EUEA-UKR-ENG-_EUEA-logo-white-1.svg","contentUrl":"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2026\/02\/Logo-EUEA-UKR-ENG-_EUEA-logo-white-1.svg","caption":"EUEA - European-Ukrainian Energy agency"},"image":{"@id":"https:\/\/euea-energyagency.org\/uk\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/euea-energyagency.org\/uk\/#\/schema\/person\/a0e8854c86806df275b9e4f1c2e6e56e","name":"Natalia Tatarchuk","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/9ef82c888699f1acdf80f3e3bc1809edf509b04f3894dabaaf7874906e77df30?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9ef82c888699f1acdf80f3e3bc1809edf509b04f3894dabaaf7874906e77df30?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ef82c888699f1acdf80f3e3bc1809edf509b04f3894dabaaf7874906e77df30?s=96&d=mm&r=g","caption":"Natalia Tatarchuk"},"url":"https:\/\/euea-energyagency.org\/en\/author\/natalia\/"}]}},"_links":{"self":[{"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/posts\/18010","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/users\/136"}],"replies":[{"embeddable":true,"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/comments?post=18010"}],"version-history":[{"count":0,"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/posts\/18010\/revisions"}],"wp:attachment":[{"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/media?parent=18010"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/categories?post=18010"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/tags?post=18010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}