{"id":20481,"date":"2020-02-06T09:59:04","date_gmt":"2020-02-06T07:59:04","guid":{"rendered":"https:\/\/euea-energyagency.org\/english-category\/news\/euea-latest-accomplishments\/smarter-finance-for-families-achievements-for-february-2020\/"},"modified":"2020-04-02T11:44:51","modified_gmt":"2020-04-02T08:44:51","slug":"smarter-finance-for-families-achievements-for-february-2020","status":"publish","type":"post","link":"https:\/\/euea-energyagency.org\/en\/news\/euea-latest-accomplishments\/smarter-finance-for-families-achievements-for-february-2020\/","title":{"rendered":"SMARTER Finance for Families achievements for February 2020"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-20477\" style=\"margin-right: auto; display: block; margin-left: auto;\" src=\"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2020\/02\/SMARTER_FEB.png\" alt=\"SMARTER FEB\" width=\"800\" height=\"444\" srcset=\"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2020\/02\/SMARTER_FEB.png 800w, https:\/\/euea-energyagency.org\/wp-content\/uploads\/2020\/02\/SMARTER_FEB-300x167.png 300w, https:\/\/euea-energyagency.org\/wp-content\/uploads\/2020\/02\/SMARTER_FEB-768x426.png 768w, https:\/\/euea-energyagency.org\/wp-content\/uploads\/2020\/02\/SMARTER_FEB-30x17.png 30w, https:\/\/euea-energyagency.org\/wp-content\/uploads\/2020\/02\/SMARTER_FEB-216x120.png 216w, https:\/\/euea-energyagency.org\/wp-content\/uploads\/2020\/02\/SMARTER_FEB-90x50.png 90w, https:\/\/euea-energyagency.org\/wp-content\/uploads\/2020\/02\/SMARTER_FEB-650x361.png 650w, https:\/\/euea-energyagency.org\/wp-content\/uploads\/2020\/02\/SMARTER_FEB-50x28.png 50w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>What an amazing beginning for <a id=\"ember1628\" class=\"hashtag-link ember-view\" href=\"https:\/\/www.linkedin.com\/feed\/hashtag\/?highlightedUpdateUrns=urn%3Ali%3Aactivity%3A6631118918977224704&amp;keywords=%23SMARTERFinance&amp;originTrackingId=jJ5Rw7ZBAtxczN0nfmWVgw%3D%3D\" target=\"_self\" rel=\"noopener noreferrer\" data-control-name=\"hashtag\">#SMARTERFinance<\/a> for Families!<\/p>\n<p>From May 2019, in 14 different countries, the project was involved in<\/p>\n<p>&#8211; 40+ conferences and events<\/p>\n<p>&#8211; 30+ meetings<\/p>\n<p>&#8211; 10+ workshops, webinars, trainings and publications<\/p>\n<p>Read more here: <a id=\"ember1633\" class=\"feed-shared-text-view__hyperlink ember-view\" tabindex=\"0\" href=\"http:\/\/bit.ly\/31tg5Uo\" target=\"_blank\" rel=\"noopener noreferrer\"><\/a><a href=\"http:\/\/bit.ly\/31tg5Uo\">http:\/\/bit.ly\/31tg5Uo<\/a><\/p>\n<p>SMARTER Finance for Families is a Horizon 2020 project to implement ambitious yet practical Green Homes &amp; Mortgage programmes in 12 European countries that includes the collaboration and participation of 17 expert green building, green energy, research and other organizations.<\/p>\n<p>EUEA is part of this project.<\/p>\n<p><img decoding=\"async\" class=\" alignleft size-full wp-image-20479\" style=\"margin-right: 10px; float: left;\" src=\"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2020\/02\/Horizon_2020.png\" alt=\"Horizon 2020\" width=\"800\" height=\"87\" srcset=\"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2020\/02\/Horizon_2020.png 800w, https:\/\/euea-energyagency.org\/wp-content\/uploads\/2020\/02\/Horizon_2020-300x33.png 300w, https:\/\/euea-energyagency.org\/wp-content\/uploads\/2020\/02\/Horizon_2020-768x84.png 768w, https:\/\/euea-energyagency.org\/wp-content\/uploads\/2020\/02\/Horizon_2020-30x3.png 30w, https:\/\/euea-energyagency.org\/wp-content\/uploads\/2020\/02\/Horizon_2020-240x26.png 240w, https:\/\/euea-energyagency.org\/wp-content\/uploads\/2020\/02\/Horizon_2020-460x50.png 460w, https:\/\/euea-energyagency.org\/wp-content\/uploads\/2020\/02\/Horizon_2020-650x71.png 650w, https:\/\/euea-energyagency.org\/wp-content\/uploads\/2020\/02\/Horizon_2020-50x5.png 50w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>What an amazing beginning for #SMARTERFinance for Families! From May 2019, in 14 different countries, the project was involved in [&hellip;]<\/p>\n","protected":false},"author":135,"featured_media":20477,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[124,153],"tags":[],"class_list":["post-20481","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-euea-latest-accomplishments","category-smarter-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SMARTER Finance for Families achievements for February 2020 - EUEA - European-Ukrainian Energy agency<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/euea-energyagency.org\/en\/news\/euea-latest-accomplishments\/smarter-finance-for-families-achievements-for-february-2020\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SMARTER Finance for Families achievements for February 2020 - EUEA - European-Ukrainian Energy agency\" \/>\n<meta property=\"og:description\" content=\"What an amazing beginning for #SMARTERFinance for Families! From May 2019, in 14 different countries, the project was involved in [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/euea-energyagency.org\/en\/news\/euea-latest-accomplishments\/smarter-finance-for-families-achievements-for-february-2020\/\" \/>\n<meta property=\"og:site_name\" content=\"EUEA - European-Ukrainian Energy agency\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-06T07:59:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-02T08:44:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2020\/02\/SMARTER_FEB.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"444\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"EUEA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"EUEA\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/euea-latest-accomplishments\\\/smarter-finance-for-families-achievements-for-february-2020\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/euea-latest-accomplishments\\\/smarter-finance-for-families-achievements-for-february-2020\\\/\"},\"author\":{\"name\":\"EUEA\",\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#\\\/schema\\\/person\\\/0d4b5fa6e9f2065620b867ea1de7ffd0\"},\"headline\":\"SMARTER Finance for Families achievements for February 2020\",\"datePublished\":\"2020-02-06T07:59:04+00:00\",\"dateModified\":\"2020-04-02T08:44:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/euea-latest-accomplishments\\\/smarter-finance-for-families-achievements-for-february-2020\\\/\"},\"wordCount\":88,\"publisher\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/euea-latest-accomplishments\\\/smarter-finance-for-families-achievements-for-february-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/euea-energyagency.org\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/SMARTER_FEB.png\",\"articleSection\":[\"EUEA latest Accomplishments\",\"SMARTER\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/euea-latest-accomplishments\\\/smarter-finance-for-families-achievements-for-february-2020\\\/\",\"url\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/euea-latest-accomplishments\\\/smarter-finance-for-families-achievements-for-february-2020\\\/\",\"name\":\"SMARTER Finance for Families achievements for February 2020 - EUEA - European-Ukrainian Energy agency\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/euea-latest-accomplishments\\\/smarter-finance-for-families-achievements-for-february-2020\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/euea-latest-accomplishments\\\/smarter-finance-for-families-achievements-for-february-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/euea-energyagency.org\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/SMARTER_FEB.png\",\"datePublished\":\"2020-02-06T07:59:04+00:00\",\"dateModified\":\"2020-04-02T08:44:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/euea-latest-accomplishments\\\/smarter-finance-for-families-achievements-for-february-2020\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/euea-latest-accomplishments\\\/smarter-finance-for-families-achievements-for-february-2020\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/euea-latest-accomplishments\\\/smarter-finance-for-families-achievements-for-february-2020\\\/#primaryimage\",\"url\":\"https:\\\/\\\/euea-energyagency.org\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/SMARTER_FEB.png\",\"contentUrl\":\"https:\\\/\\\/euea-energyagency.org\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/SMARTER_FEB.png\",\"width\":800,\"height\":444,\"caption\":\"SMARTER FEB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/euea-latest-accomplishments\\\/smarter-finance-for-families-achievements-for-february-2020\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043e\u043b\u043e\u0432\u043d\u0430\",\"item\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SMARTER Finance for Families achievements for February 2020\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#website\",\"url\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/\",\"name\":\"EUEA - European-Ukrainian Energy agency\",\"description\":\"EUEA - European-Ukrainian Energy agency\",\"publisher\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#organization\",\"name\":\"EUEA - European-Ukrainian Energy agency\",\"url\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/euea-energyagency.org\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Logo-EUEA-UKR-ENG-_EUEA-logo-white-1.svg\",\"contentUrl\":\"https:\\\/\\\/euea-energyagency.org\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Logo-EUEA-UKR-ENG-_EUEA-logo-white-1.svg\",\"caption\":\"EUEA - European-Ukrainian Energy agency\"},\"image\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#\\\/schema\\\/person\\\/0d4b5fa6e9f2065620b867ea1de7ffd0\",\"name\":\"EUEA\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b17e2d7ab1eb40161e8c143623457b3ff1d88d77beae69e516f93059c9744e2e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b17e2d7ab1eb40161e8c143623457b3ff1d88d77beae69e516f93059c9744e2e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b17e2d7ab1eb40161e8c143623457b3ff1d88d77beae69e516f93059c9744e2e?s=96&d=mm&r=g\",\"caption\":\"EUEA\"},\"url\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/author\\\/david\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SMARTER Finance for Families achievements for February 2020 - EUEA - European-Ukrainian Energy agency","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/euea-energyagency.org\/en\/news\/euea-latest-accomplishments\/smarter-finance-for-families-achievements-for-february-2020\/","og_locale":"en_US","og_type":"article","og_title":"SMARTER Finance for Families achievements for February 2020 - EUEA - European-Ukrainian Energy agency","og_description":"What an amazing beginning for #SMARTERFinance for Families! From May 2019, in 14 different countries, the project was involved in [&hellip;]","og_url":"https:\/\/euea-energyagency.org\/en\/news\/euea-latest-accomplishments\/smarter-finance-for-families-achievements-for-february-2020\/","og_site_name":"EUEA - European-Ukrainian Energy agency","article_published_time":"2020-02-06T07:59:04+00:00","article_modified_time":"2020-04-02T08:44:51+00:00","og_image":[{"width":800,"height":444,"url":"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2020\/02\/SMARTER_FEB.png","type":"image\/png"}],"author":"EUEA","twitter_card":"summary_large_image","twitter_misc":{"Written by":"EUEA"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/euea-energyagency.org\/en\/news\/euea-latest-accomplishments\/smarter-finance-for-families-achievements-for-february-2020\/#article","isPartOf":{"@id":"https:\/\/euea-energyagency.org\/en\/news\/euea-latest-accomplishments\/smarter-finance-for-families-achievements-for-february-2020\/"},"author":{"name":"EUEA","@id":"https:\/\/euea-energyagency.org\/uk\/#\/schema\/person\/0d4b5fa6e9f2065620b867ea1de7ffd0"},"headline":"SMARTER Finance for Families achievements for February 2020","datePublished":"2020-02-06T07:59:04+00:00","dateModified":"2020-04-02T08:44:51+00:00","mainEntityOfPage":{"@id":"https:\/\/euea-energyagency.org\/en\/news\/euea-latest-accomplishments\/smarter-finance-for-families-achievements-for-february-2020\/"},"wordCount":88,"publisher":{"@id":"https:\/\/euea-energyagency.org\/uk\/#organization"},"image":{"@id":"https:\/\/euea-energyagency.org\/en\/news\/euea-latest-accomplishments\/smarter-finance-for-families-achievements-for-february-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2020\/02\/SMARTER_FEB.png","articleSection":["EUEA latest Accomplishments","SMARTER"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/euea-energyagency.org\/en\/news\/euea-latest-accomplishments\/smarter-finance-for-families-achievements-for-february-2020\/","url":"https:\/\/euea-energyagency.org\/en\/news\/euea-latest-accomplishments\/smarter-finance-for-families-achievements-for-february-2020\/","name":"SMARTER Finance for Families achievements for February 2020 - EUEA - European-Ukrainian Energy agency","isPartOf":{"@id":"https:\/\/euea-energyagency.org\/uk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/euea-energyagency.org\/en\/news\/euea-latest-accomplishments\/smarter-finance-for-families-achievements-for-february-2020\/#primaryimage"},"image":{"@id":"https:\/\/euea-energyagency.org\/en\/news\/euea-latest-accomplishments\/smarter-finance-for-families-achievements-for-february-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2020\/02\/SMARTER_FEB.png","datePublished":"2020-02-06T07:59:04+00:00","dateModified":"2020-04-02T08:44:51+00:00","breadcrumb":{"@id":"https:\/\/euea-energyagency.org\/en\/news\/euea-latest-accomplishments\/smarter-finance-for-families-achievements-for-february-2020\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/euea-energyagency.org\/en\/news\/euea-latest-accomplishments\/smarter-finance-for-families-achievements-for-february-2020\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/euea-energyagency.org\/en\/news\/euea-latest-accomplishments\/smarter-finance-for-families-achievements-for-february-2020\/#primaryimage","url":"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2020\/02\/SMARTER_FEB.png","contentUrl":"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2020\/02\/SMARTER_FEB.png","width":800,"height":444,"caption":"SMARTER FEB"},{"@type":"BreadcrumbList","@id":"https:\/\/euea-energyagency.org\/en\/news\/euea-latest-accomplishments\/smarter-finance-for-families-achievements-for-february-2020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043e\u043b\u043e\u0432\u043d\u0430","item":"https:\/\/euea-energyagency.org\/uk\/"},{"@type":"ListItem","position":2,"name":"SMARTER Finance for Families achievements for February 2020"}]},{"@type":"WebSite","@id":"https:\/\/euea-energyagency.org\/uk\/#website","url":"https:\/\/euea-energyagency.org\/uk\/","name":"EUEA - European-Ukrainian Energy agency","description":"EUEA - European-Ukrainian Energy agency","publisher":{"@id":"https:\/\/euea-energyagency.org\/uk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/euea-energyagency.org\/uk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/euea-energyagency.org\/uk\/#organization","name":"EUEA - European-Ukrainian Energy agency","url":"https:\/\/euea-energyagency.org\/uk\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/euea-energyagency.org\/uk\/#\/schema\/logo\/image\/","url":"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2026\/02\/Logo-EUEA-UKR-ENG-_EUEA-logo-white-1.svg","contentUrl":"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2026\/02\/Logo-EUEA-UKR-ENG-_EUEA-logo-white-1.svg","caption":"EUEA - European-Ukrainian Energy agency"},"image":{"@id":"https:\/\/euea-energyagency.org\/uk\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/euea-energyagency.org\/uk\/#\/schema\/person\/0d4b5fa6e9f2065620b867ea1de7ffd0","name":"EUEA","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/b17e2d7ab1eb40161e8c143623457b3ff1d88d77beae69e516f93059c9744e2e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b17e2d7ab1eb40161e8c143623457b3ff1d88d77beae69e516f93059c9744e2e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b17e2d7ab1eb40161e8c143623457b3ff1d88d77beae69e516f93059c9744e2e?s=96&d=mm&r=g","caption":"EUEA"},"url":"https:\/\/euea-energyagency.org\/en\/author\/david\/"}]}},"_links":{"self":[{"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/posts\/20481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/users\/135"}],"replies":[{"embeddable":true,"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/comments?post=20481"}],"version-history":[{"count":1,"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/posts\/20481\/revisions"}],"predecessor-version":[{"id":21064,"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/posts\/20481\/revisions\/21064"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/media\/20477"}],"wp:attachment":[{"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/media?parent=20481"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/categories?post=20481"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/tags?post=20481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}