{"id":24746,"date":"2021-02-19T09:34:00","date_gmt":"2021-02-19T07:34:00","guid":{"rendered":"https:\/\/euea-energyagency.org\/?p=24746"},"modified":"2021-02-19T09:34:00","modified_gmt":"2021-02-19T07:34:00","slug":"euea-personal-meeting-with-yuriy-vitrenko-acting-ministry-of-energy","status":"publish","type":"post","link":"https:\/\/euea-energyagency.org\/en\/news\/market-news\/euea-personal-meeting-with-yuriy-vitrenko-acting-ministry-of-energy\/","title":{"rendered":"EUEA personal meeting with Yuriy Vitrenko, Acting Ministry of Energy"},"content":{"rendered":"<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">On February 18, EUEA took part in a personal meeting with Yuriy Vitrenko, Acting Ministry of Energy, in order to establish a dialogue and identify a common solution and urgent problems in renewable energy and sustainable long-term development. There was an open dialogue and exchange of views, and then fruitful work ahead.<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">EUEA Board members on the meeting on behalf of EUEA:<\/div>\n<div dir=\"auto\">Alina Sviderska (Scatec Solar);<\/div>\n<div dir=\"auto\">Anton Mishyn (DTEK RES), EUEA Board Member;<\/div>\n<div dir=\"auto\">Magnus Johansen (NBT);<\/div>\n<div dir=\"auto\">Max Lebedev (GOLAW), EUEA Vice-Chair of the Board;<\/div>\n<div dir=\"auto\">Oleksandra Gumeniuk, EUEA Director;<\/div>\n<div dir=\"auto\">Yuri Kubrushko (IMEPOWER), EUEA Board Member.<\/div>\n<div dir=\"auto\"><\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">More about the meeting: <a class=\"oajrlxb2 g5ia77u1 qu0x051f esr5mh6w e9989ue4 r7d6kgcz rq0escxv nhd2j8a9 nc684nl6 p7hjln8o kvgmc6g5 cxmmr5t8 oygrvhab hcukyx3x jb3vyjys rz4wbd8a qt6c0cv9 a8nywdso i1ao9s8h esuyzwwr f1sip0of lzcic4wl py34i1dx gpro0wi8\" tabindex=\"0\" role=\"link\" href=\"https:\/\/cutt.ly\/rk6REcu?fbclid=IwAR3t4q4xLaNhkpMLs1pFMQ3wjnpFHBQLy2iT-v6x5N3BE5LvLBrlv3glw68\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">https:\/\/cutt.ly\/rk6REcu<\/a><\/div>\n<\/div>\n<div dir=\"auto\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-24736 alignleft\" src=\"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2021\/02\/IMG_7148-20.jpg\" alt=\"\" width=\"554\" height=\"337\" \/><img decoding=\"async\" class=\" wp-image-24738 alignleft\" src=\"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2021\/02\/IMG_7122-8.jpg\" alt=\"\" width=\"556\" height=\"368\" \/><img decoding=\"async\" class=\" wp-image-24740 alignleft\" src=\"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2021\/02\/IMG_7115-6.jpg\" alt=\"\" width=\"548\" height=\"384\" \/><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-24742 alignleft\" src=\"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2021\/02\/IMG_7106-3-1.jpg\" alt=\"\" width=\"541\" height=\"406\" \/><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-24744 alignleft\" src=\"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2021\/02\/IMG_7143-15.jpg\" alt=\"\" width=\"531\" height=\"300\" \/><\/div>\n","protected":false},"excerpt":{"rendered":"<p>On February 18, EUEA took part in a personal meeting with Yuriy Vitrenko, Acting Ministry of Energy, in order to [&hellip;]<\/p>\n","protected":false},"author":135,"featured_media":24736,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[125],"tags":[],"class_list":["post-24746","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-market-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EUEA personal meeting with Yuriy Vitrenko, Acting Ministry of Energy - EUEA - European-Ukrainian Energy agency<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/euea-energyagency.org\/en\/news\/market-news\/euea-personal-meeting-with-yuriy-vitrenko-acting-ministry-of-energy\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EUEA personal meeting with Yuriy Vitrenko, Acting Ministry of Energy - EUEA - European-Ukrainian Energy agency\" \/>\n<meta property=\"og:description\" content=\"On February 18, EUEA took part in a personal meeting with Yuriy Vitrenko, Acting Ministry of Energy, in order to [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/euea-energyagency.org\/en\/news\/market-news\/euea-personal-meeting-with-yuriy-vitrenko-acting-ministry-of-energy\/\" \/>\n<meta property=\"og:site_name\" content=\"EUEA - European-Ukrainian Energy agency\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-19T07:34:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2021\/02\/IMG_7148-20-1024x623.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"623\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"EUEA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"EUEA\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/market-news\\\/euea-personal-meeting-with-yuriy-vitrenko-acting-ministry-of-energy\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/market-news\\\/euea-personal-meeting-with-yuriy-vitrenko-acting-ministry-of-energy\\\/\"},\"author\":{\"name\":\"EUEA\",\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#\\\/schema\\\/person\\\/0d4b5fa6e9f2065620b867ea1de7ffd0\"},\"headline\":\"EUEA personal meeting with Yuriy Vitrenko, Acting Ministry of Energy\",\"datePublished\":\"2021-02-19T07:34:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/market-news\\\/euea-personal-meeting-with-yuriy-vitrenko-acting-ministry-of-energy\\\/\"},\"wordCount\":112,\"publisher\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/market-news\\\/euea-personal-meeting-with-yuriy-vitrenko-acting-ministry-of-energy\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/euea-energyagency.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/IMG_7148-20.jpg\",\"articleSection\":[\"Market news\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/market-news\\\/euea-personal-meeting-with-yuriy-vitrenko-acting-ministry-of-energy\\\/\",\"url\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/market-news\\\/euea-personal-meeting-with-yuriy-vitrenko-acting-ministry-of-energy\\\/\",\"name\":\"EUEA personal meeting with Yuriy Vitrenko, Acting Ministry of Energy - EUEA - European-Ukrainian Energy agency\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/market-news\\\/euea-personal-meeting-with-yuriy-vitrenko-acting-ministry-of-energy\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/market-news\\\/euea-personal-meeting-with-yuriy-vitrenko-acting-ministry-of-energy\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/euea-energyagency.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/IMG_7148-20.jpg\",\"datePublished\":\"2021-02-19T07:34:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/market-news\\\/euea-personal-meeting-with-yuriy-vitrenko-acting-ministry-of-energy\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/market-news\\\/euea-personal-meeting-with-yuriy-vitrenko-acting-ministry-of-energy\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/market-news\\\/euea-personal-meeting-with-yuriy-vitrenko-acting-ministry-of-energy\\\/#primaryimage\",\"url\":\"https:\\\/\\\/euea-energyagency.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/IMG_7148-20.jpg\",\"contentUrl\":\"https:\\\/\\\/euea-energyagency.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/IMG_7148-20.jpg\",\"width\":2560,\"height\":1556},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/market-news\\\/euea-personal-meeting-with-yuriy-vitrenko-acting-ministry-of-energy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043e\u043b\u043e\u0432\u043d\u0430\",\"item\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EUEA personal meeting with Yuriy Vitrenko, Acting Ministry of Energy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#website\",\"url\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/\",\"name\":\"EUEA - European-Ukrainian Energy agency\",\"description\":\"EUEA - European-Ukrainian Energy agency\",\"publisher\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#organization\",\"name\":\"EUEA - European-Ukrainian Energy agency\",\"url\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/euea-energyagency.org\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Logo-EUEA-UKR-ENG-_EUEA-logo-white-1.svg\",\"contentUrl\":\"https:\\\/\\\/euea-energyagency.org\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Logo-EUEA-UKR-ENG-_EUEA-logo-white-1.svg\",\"caption\":\"EUEA - European-Ukrainian Energy agency\"},\"image\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#\\\/schema\\\/person\\\/0d4b5fa6e9f2065620b867ea1de7ffd0\",\"name\":\"EUEA\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b17e2d7ab1eb40161e8c143623457b3ff1d88d77beae69e516f93059c9744e2e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b17e2d7ab1eb40161e8c143623457b3ff1d88d77beae69e516f93059c9744e2e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b17e2d7ab1eb40161e8c143623457b3ff1d88d77beae69e516f93059c9744e2e?s=96&d=mm&r=g\",\"caption\":\"EUEA\"},\"url\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/author\\\/david\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EUEA personal meeting with Yuriy Vitrenko, Acting Ministry of Energy - EUEA - European-Ukrainian Energy agency","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/euea-energyagency.org\/en\/news\/market-news\/euea-personal-meeting-with-yuriy-vitrenko-acting-ministry-of-energy\/","og_locale":"en_US","og_type":"article","og_title":"EUEA personal meeting with Yuriy Vitrenko, Acting Ministry of Energy - EUEA - European-Ukrainian Energy agency","og_description":"On February 18, EUEA took part in a personal meeting with Yuriy Vitrenko, Acting Ministry of Energy, in order to [&hellip;]","og_url":"https:\/\/euea-energyagency.org\/en\/news\/market-news\/euea-personal-meeting-with-yuriy-vitrenko-acting-ministry-of-energy\/","og_site_name":"EUEA - European-Ukrainian Energy agency","article_published_time":"2021-02-19T07:34:00+00:00","og_image":[{"width":1024,"height":623,"url":"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2021\/02\/IMG_7148-20-1024x623.jpg","type":"image\/jpeg"}],"author":"EUEA","twitter_card":"summary_large_image","twitter_misc":{"Written by":"EUEA","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/euea-energyagency.org\/en\/news\/market-news\/euea-personal-meeting-with-yuriy-vitrenko-acting-ministry-of-energy\/#article","isPartOf":{"@id":"https:\/\/euea-energyagency.org\/en\/news\/market-news\/euea-personal-meeting-with-yuriy-vitrenko-acting-ministry-of-energy\/"},"author":{"name":"EUEA","@id":"https:\/\/euea-energyagency.org\/uk\/#\/schema\/person\/0d4b5fa6e9f2065620b867ea1de7ffd0"},"headline":"EUEA personal meeting with Yuriy Vitrenko, Acting Ministry of Energy","datePublished":"2021-02-19T07:34:00+00:00","mainEntityOfPage":{"@id":"https:\/\/euea-energyagency.org\/en\/news\/market-news\/euea-personal-meeting-with-yuriy-vitrenko-acting-ministry-of-energy\/"},"wordCount":112,"publisher":{"@id":"https:\/\/euea-energyagency.org\/uk\/#organization"},"image":{"@id":"https:\/\/euea-energyagency.org\/en\/news\/market-news\/euea-personal-meeting-with-yuriy-vitrenko-acting-ministry-of-energy\/#primaryimage"},"thumbnailUrl":"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2021\/02\/IMG_7148-20.jpg","articleSection":["Market news"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/euea-energyagency.org\/en\/news\/market-news\/euea-personal-meeting-with-yuriy-vitrenko-acting-ministry-of-energy\/","url":"https:\/\/euea-energyagency.org\/en\/news\/market-news\/euea-personal-meeting-with-yuriy-vitrenko-acting-ministry-of-energy\/","name":"EUEA personal meeting with Yuriy Vitrenko, Acting Ministry of Energy - EUEA - European-Ukrainian Energy agency","isPartOf":{"@id":"https:\/\/euea-energyagency.org\/uk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/euea-energyagency.org\/en\/news\/market-news\/euea-personal-meeting-with-yuriy-vitrenko-acting-ministry-of-energy\/#primaryimage"},"image":{"@id":"https:\/\/euea-energyagency.org\/en\/news\/market-news\/euea-personal-meeting-with-yuriy-vitrenko-acting-ministry-of-energy\/#primaryimage"},"thumbnailUrl":"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2021\/02\/IMG_7148-20.jpg","datePublished":"2021-02-19T07:34:00+00:00","breadcrumb":{"@id":"https:\/\/euea-energyagency.org\/en\/news\/market-news\/euea-personal-meeting-with-yuriy-vitrenko-acting-ministry-of-energy\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/euea-energyagency.org\/en\/news\/market-news\/euea-personal-meeting-with-yuriy-vitrenko-acting-ministry-of-energy\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/euea-energyagency.org\/en\/news\/market-news\/euea-personal-meeting-with-yuriy-vitrenko-acting-ministry-of-energy\/#primaryimage","url":"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2021\/02\/IMG_7148-20.jpg","contentUrl":"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2021\/02\/IMG_7148-20.jpg","width":2560,"height":1556},{"@type":"BreadcrumbList","@id":"https:\/\/euea-energyagency.org\/en\/news\/market-news\/euea-personal-meeting-with-yuriy-vitrenko-acting-ministry-of-energy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043e\u043b\u043e\u0432\u043d\u0430","item":"https:\/\/euea-energyagency.org\/uk\/"},{"@type":"ListItem","position":2,"name":"EUEA personal meeting with Yuriy Vitrenko, Acting Ministry of Energy"}]},{"@type":"WebSite","@id":"https:\/\/euea-energyagency.org\/uk\/#website","url":"https:\/\/euea-energyagency.org\/uk\/","name":"EUEA - European-Ukrainian Energy agency","description":"EUEA - European-Ukrainian Energy agency","publisher":{"@id":"https:\/\/euea-energyagency.org\/uk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/euea-energyagency.org\/uk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/euea-energyagency.org\/uk\/#organization","name":"EUEA - European-Ukrainian Energy agency","url":"https:\/\/euea-energyagency.org\/uk\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/euea-energyagency.org\/uk\/#\/schema\/logo\/image\/","url":"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2026\/02\/Logo-EUEA-UKR-ENG-_EUEA-logo-white-1.svg","contentUrl":"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2026\/02\/Logo-EUEA-UKR-ENG-_EUEA-logo-white-1.svg","caption":"EUEA - European-Ukrainian Energy agency"},"image":{"@id":"https:\/\/euea-energyagency.org\/uk\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/euea-energyagency.org\/uk\/#\/schema\/person\/0d4b5fa6e9f2065620b867ea1de7ffd0","name":"EUEA","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/b17e2d7ab1eb40161e8c143623457b3ff1d88d77beae69e516f93059c9744e2e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b17e2d7ab1eb40161e8c143623457b3ff1d88d77beae69e516f93059c9744e2e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b17e2d7ab1eb40161e8c143623457b3ff1d88d77beae69e516f93059c9744e2e?s=96&d=mm&r=g","caption":"EUEA"},"url":"https:\/\/euea-energyagency.org\/en\/author\/david\/"}]}},"_links":{"self":[{"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/posts\/24746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/users\/135"}],"replies":[{"embeddable":true,"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/comments?post=24746"}],"version-history":[{"count":1,"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/posts\/24746\/revisions"}],"predecessor-version":[{"id":24747,"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/posts\/24746\/revisions\/24747"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/media\/24736"}],"wp:attachment":[{"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/media?parent=24746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/categories?post=24746"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/tags?post=24746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}