{"id":27520,"date":"2021-12-21T13:25:24","date_gmt":"2021-12-21T11:25:24","guid":{"rendered":"https:\/\/euea-energyagency.org\/?p=27520"},"modified":"2022-01-05T16:54:19","modified_gmt":"2022-01-05T14:54:19","slug":"euea-and-unido-launched-the-all-ukrainian-award-pacesetters-for-energy-management27520","status":"publish","type":"post","link":"https:\/\/euea-energyagency.org\/en\/news\/euea-latest-accomplishments\/euea-and-unido-launched-the-all-ukrainian-award-pacesetters-for-energy-management27520\/","title":{"rendered":"EUEA and UNIDO launched The All-Ukrainian Award: Pacesetters for Energy Management"},"content":{"rendered":"<p class=\"p1\" style=\"text-align: justify;\">We are pleased to announce that EUEA and UNIDO launched The All-Ukrainian Award: Pacesetters for Energy Management.<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">The All-Ukrainian Award: Pacesetters for Energy Management is the first of its kind in Ukraine, which recognizes leading organizations for their energy management achievements.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p class=\"p1\" style=\"text-align: justify;\">The purpose of this program is to attract the attention of the industrial sector to global energy and climate issues and demonstrate results in improving the energy efficiency of production through the introduction of energy management.<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Also, &#8220;All-Ukrainian Award: Pacesetters for Energy Management&#8221; aims to promote the implementation of energy management systems and increase energy efficiency in industry, which is one of the policy priorities of Ukraine in the field of energy efficiency.<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">All detailed information is published on the EUEA website and on Facebook page: <a href=\"https:\/\/www.facebook.com\/AwardEnMS\/\">https:\/\/www.facebook.com\/AwardEnMS\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>We are pleased to announce that EUEA and UNIDO launched The All-Ukrainian Award: Pacesetters for Energy Management. The All-Ukrainian Award: [&hellip;]<\/p>\n","protected":false},"author":135,"featured_media":27357,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[124,125],"tags":[],"class_list":["post-27520","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-euea-latest-accomplishments","category-market-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EUEA and UNIDO launched The All-Ukrainian Award: Pacesetters for Energy Management - EUEA - European-Ukrainian Energy agency<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/euea-energyagency.org\/en\/news\/euea-and-unido-launched-the-all-ukrainian-award-pacesetters-for-energy-management27520\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EUEA and UNIDO launched The All-Ukrainian Award: Pacesetters for Energy Management - EUEA - European-Ukrainian Energy agency\" \/>\n<meta property=\"og:description\" content=\"We are pleased to announce that EUEA and UNIDO launched The All-Ukrainian Award: Pacesetters for Energy Management. The All-Ukrainian Award: [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/euea-energyagency.org\/en\/news\/euea-and-unido-launched-the-all-ukrainian-award-pacesetters-for-energy-management27520\/\" \/>\n<meta property=\"og:site_name\" content=\"EUEA - European-Ukrainian Energy agency\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-21T11:25:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-05T14:54:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2021\/12\/FB-820h312px_FB1-1024x390.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"390\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"EUEA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"EUEA\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/euea-and-unido-launched-the-all-ukrainian-award-pacesetters-for-energy-management27520\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/euea-and-unido-launched-the-all-ukrainian-award-pacesetters-for-energy-management27520\\\/\"},\"author\":{\"name\":\"EUEA\",\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#\\\/schema\\\/person\\\/0d4b5fa6e9f2065620b867ea1de7ffd0\"},\"headline\":\"EUEA and UNIDO launched The All-Ukrainian Award: Pacesetters for Energy Management\",\"datePublished\":\"2021-12-21T11:25:24+00:00\",\"dateModified\":\"2022-01-05T14:54:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/euea-and-unido-launched-the-all-ukrainian-award-pacesetters-for-energy-management27520\\\/\"},\"wordCount\":143,\"publisher\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/euea-and-unido-launched-the-all-ukrainian-award-pacesetters-for-energy-management27520\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/euea-energyagency.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/FB-820h312px_FB1.png\",\"articleSection\":[\"EUEA latest Accomplishments\",\"Market news\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/euea-and-unido-launched-the-all-ukrainian-award-pacesetters-for-energy-management27520\\\/\",\"url\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/euea-and-unido-launched-the-all-ukrainian-award-pacesetters-for-energy-management27520\\\/\",\"name\":\"EUEA and UNIDO launched The All-Ukrainian Award: Pacesetters for Energy Management - EUEA - European-Ukrainian Energy agency\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/euea-and-unido-launched-the-all-ukrainian-award-pacesetters-for-energy-management27520\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/euea-and-unido-launched-the-all-ukrainian-award-pacesetters-for-energy-management27520\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/euea-energyagency.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/FB-820h312px_FB1.png\",\"datePublished\":\"2021-12-21T11:25:24+00:00\",\"dateModified\":\"2022-01-05T14:54:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/euea-and-unido-launched-the-all-ukrainian-award-pacesetters-for-energy-management27520\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/euea-and-unido-launched-the-all-ukrainian-award-pacesetters-for-energy-management27520\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/euea-and-unido-launched-the-all-ukrainian-award-pacesetters-for-energy-management27520\\\/#primaryimage\",\"url\":\"https:\\\/\\\/euea-energyagency.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/FB-820h312px_FB1.png\",\"contentUrl\":\"https:\\\/\\\/euea-energyagency.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/FB-820h312px_FB1.png\",\"width\":3417,\"height\":1301},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/news\\\/euea-and-unido-launched-the-all-ukrainian-award-pacesetters-for-energy-management27520\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043e\u043b\u043e\u0432\u043d\u0430\",\"item\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EUEA and UNIDO launched The All-Ukrainian Award: Pacesetters for Energy Management\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#website\",\"url\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/\",\"name\":\"EUEA - European-Ukrainian Energy agency\",\"description\":\"EUEA - European-Ukrainian Energy agency\",\"publisher\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#organization\",\"name\":\"EUEA - European-Ukrainian Energy agency\",\"url\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/euea-energyagency.org\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Logo-EUEA-UKR-ENG-_EUEA-logo-white-1.svg\",\"contentUrl\":\"https:\\\/\\\/euea-energyagency.org\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Logo-EUEA-UKR-ENG-_EUEA-logo-white-1.svg\",\"caption\":\"EUEA - European-Ukrainian Energy agency\"},\"image\":{\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/euea-energyagency.org\\\/uk\\\/#\\\/schema\\\/person\\\/0d4b5fa6e9f2065620b867ea1de7ffd0\",\"name\":\"EUEA\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b17e2d7ab1eb40161e8c143623457b3ff1d88d77beae69e516f93059c9744e2e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b17e2d7ab1eb40161e8c143623457b3ff1d88d77beae69e516f93059c9744e2e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b17e2d7ab1eb40161e8c143623457b3ff1d88d77beae69e516f93059c9744e2e?s=96&d=mm&r=g\",\"caption\":\"EUEA\"},\"url\":\"https:\\\/\\\/euea-energyagency.org\\\/en\\\/author\\\/david\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EUEA and UNIDO launched The All-Ukrainian Award: Pacesetters for Energy Management - EUEA - European-Ukrainian Energy agency","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/euea-energyagency.org\/en\/news\/euea-and-unido-launched-the-all-ukrainian-award-pacesetters-for-energy-management27520\/","og_locale":"en_US","og_type":"article","og_title":"EUEA and UNIDO launched The All-Ukrainian Award: Pacesetters for Energy Management - EUEA - European-Ukrainian Energy agency","og_description":"We are pleased to announce that EUEA and UNIDO launched The All-Ukrainian Award: Pacesetters for Energy Management. The All-Ukrainian Award: [&hellip;]","og_url":"https:\/\/euea-energyagency.org\/en\/news\/euea-and-unido-launched-the-all-ukrainian-award-pacesetters-for-energy-management27520\/","og_site_name":"EUEA - European-Ukrainian Energy agency","article_published_time":"2021-12-21T11:25:24+00:00","article_modified_time":"2022-01-05T14:54:19+00:00","og_image":[{"width":1024,"height":390,"url":"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2021\/12\/FB-820h312px_FB1-1024x390.png","type":"image\/png"}],"author":"EUEA","twitter_card":"summary_large_image","twitter_misc":{"Written by":"EUEA","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/euea-energyagency.org\/en\/news\/euea-and-unido-launched-the-all-ukrainian-award-pacesetters-for-energy-management27520\/#article","isPartOf":{"@id":"https:\/\/euea-energyagency.org\/en\/news\/euea-and-unido-launched-the-all-ukrainian-award-pacesetters-for-energy-management27520\/"},"author":{"name":"EUEA","@id":"https:\/\/euea-energyagency.org\/uk\/#\/schema\/person\/0d4b5fa6e9f2065620b867ea1de7ffd0"},"headline":"EUEA and UNIDO launched The All-Ukrainian Award: Pacesetters for Energy Management","datePublished":"2021-12-21T11:25:24+00:00","dateModified":"2022-01-05T14:54:19+00:00","mainEntityOfPage":{"@id":"https:\/\/euea-energyagency.org\/en\/news\/euea-and-unido-launched-the-all-ukrainian-award-pacesetters-for-energy-management27520\/"},"wordCount":143,"publisher":{"@id":"https:\/\/euea-energyagency.org\/uk\/#organization"},"image":{"@id":"https:\/\/euea-energyagency.org\/en\/news\/euea-and-unido-launched-the-all-ukrainian-award-pacesetters-for-energy-management27520\/#primaryimage"},"thumbnailUrl":"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2021\/12\/FB-820h312px_FB1.png","articleSection":["EUEA latest Accomplishments","Market news"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/euea-energyagency.org\/en\/news\/euea-and-unido-launched-the-all-ukrainian-award-pacesetters-for-energy-management27520\/","url":"https:\/\/euea-energyagency.org\/en\/news\/euea-and-unido-launched-the-all-ukrainian-award-pacesetters-for-energy-management27520\/","name":"EUEA and UNIDO launched The All-Ukrainian Award: Pacesetters for Energy Management - EUEA - European-Ukrainian Energy agency","isPartOf":{"@id":"https:\/\/euea-energyagency.org\/uk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/euea-energyagency.org\/en\/news\/euea-and-unido-launched-the-all-ukrainian-award-pacesetters-for-energy-management27520\/#primaryimage"},"image":{"@id":"https:\/\/euea-energyagency.org\/en\/news\/euea-and-unido-launched-the-all-ukrainian-award-pacesetters-for-energy-management27520\/#primaryimage"},"thumbnailUrl":"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2021\/12\/FB-820h312px_FB1.png","datePublished":"2021-12-21T11:25:24+00:00","dateModified":"2022-01-05T14:54:19+00:00","breadcrumb":{"@id":"https:\/\/euea-energyagency.org\/en\/news\/euea-and-unido-launched-the-all-ukrainian-award-pacesetters-for-energy-management27520\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/euea-energyagency.org\/en\/news\/euea-and-unido-launched-the-all-ukrainian-award-pacesetters-for-energy-management27520\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/euea-energyagency.org\/en\/news\/euea-and-unido-launched-the-all-ukrainian-award-pacesetters-for-energy-management27520\/#primaryimage","url":"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2021\/12\/FB-820h312px_FB1.png","contentUrl":"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2021\/12\/FB-820h312px_FB1.png","width":3417,"height":1301},{"@type":"BreadcrumbList","@id":"https:\/\/euea-energyagency.org\/en\/news\/euea-and-unido-launched-the-all-ukrainian-award-pacesetters-for-energy-management27520\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043e\u043b\u043e\u0432\u043d\u0430","item":"https:\/\/euea-energyagency.org\/uk\/"},{"@type":"ListItem","position":2,"name":"EUEA and UNIDO launched The All-Ukrainian Award: Pacesetters for Energy Management"}]},{"@type":"WebSite","@id":"https:\/\/euea-energyagency.org\/uk\/#website","url":"https:\/\/euea-energyagency.org\/uk\/","name":"EUEA - European-Ukrainian Energy agency","description":"EUEA - European-Ukrainian Energy agency","publisher":{"@id":"https:\/\/euea-energyagency.org\/uk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/euea-energyagency.org\/uk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/euea-energyagency.org\/uk\/#organization","name":"EUEA - European-Ukrainian Energy agency","url":"https:\/\/euea-energyagency.org\/uk\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/euea-energyagency.org\/uk\/#\/schema\/logo\/image\/","url":"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2026\/02\/Logo-EUEA-UKR-ENG-_EUEA-logo-white-1.svg","contentUrl":"https:\/\/euea-energyagency.org\/wp-content\/uploads\/2026\/02\/Logo-EUEA-UKR-ENG-_EUEA-logo-white-1.svg","caption":"EUEA - European-Ukrainian Energy agency"},"image":{"@id":"https:\/\/euea-energyagency.org\/uk\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/euea-energyagency.org\/uk\/#\/schema\/person\/0d4b5fa6e9f2065620b867ea1de7ffd0","name":"EUEA","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/b17e2d7ab1eb40161e8c143623457b3ff1d88d77beae69e516f93059c9744e2e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b17e2d7ab1eb40161e8c143623457b3ff1d88d77beae69e516f93059c9744e2e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b17e2d7ab1eb40161e8c143623457b3ff1d88d77beae69e516f93059c9744e2e?s=96&d=mm&r=g","caption":"EUEA"},"url":"https:\/\/euea-energyagency.org\/en\/author\/david\/"}]}},"_links":{"self":[{"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/posts\/27520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/users\/135"}],"replies":[{"embeddable":true,"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/comments?post=27520"}],"version-history":[{"count":2,"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/posts\/27520\/revisions"}],"predecessor-version":[{"id":27697,"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/posts\/27520\/revisions\/27697"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/media\/27357"}],"wp:attachment":[{"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/media?parent=27520"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/categories?post=27520"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/euea-energyagency.org\/en\/wp-json\/wp\/v2\/tags?post=27520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}